{"id":16434,"date":"2019-05-12T15:00:56","date_gmt":"2019-05-12T13:00:56","guid":{"rendered":"https:\/\/lucidmoons.com\/agb\/"},"modified":"2021-10-05T21:36:17","modified_gmt":"2021-10-05T19:36:17","slug":"agb","status":"publish","type":"page","link":"https:\/\/lucidmoons.com\/de-ch\/agb\/","title":{"rendered":"Allgemeine Gesch\u00e4ftsbedingungen (AGB)"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Allgemeine Gesch\u00e4ftsbedingungen (AGB)<\/h1>\n\n\n\n<p><em>Stand: 30.07.2018<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Geltung der Allgemeinen Gesch\u00e4ftsbedingungen<\/h2>\n\n\n\n<p>Diese Allgemeinen Gesch\u00e4ftsbedingungen (nachfolgend \u201eAGB\u201c genannt) gelten f\u00fcr alle Vertr\u00e4ge, die \u00fcber den Online-Shop www.lucidmoons.com zwischen der Lucid Moons GmbH und Kunden abgeschlossen werden, die Verbraucher sind.<\/p>\n\n\n\n<p>Verbraucher ist jede nat\u00fcrliche Person, die ein Rechtsgesch\u00e4ft zu einem Zwecke abschliesst, der weder ihrer gewerblichen noch ihrer selbstst\u00e4ndigen beruflichen T\u00e4tigkeit zugerechnet werden kann.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">1. Bestimmungen<\/h2>\n\n\n\n<p>Willkommen auf der Webseite von Lucid Moons (die \u201eWebsite\u201c) einer Familie von Webseiten, bestehend aus unseren l\u00e4nderspezifischen Websites, mobilen Websites, mobilen Apps und Blogs. Diese Lucid Moons-Nutzungsbedingungen (\u201eNutzungsbedingungen\u201c) legen die Vereinbarung zwischen Lucid Moons GmbH. (\u00abLucid Moons\u00bb), verbundenen Unternehmen von Lucid Moons fest und jeder Benutzer (\u201eBenutzer\u201c, \u201eIhre\u201c oder \u201eSie\u201c), die Ihre Nutzung der Website, und der Datenschutzrichtlinie (\u201eDatenschutzrichtlinie\u201c) regeln.<\/p>\n\n\n\n<p>Bitte lesen Sie diese Vereinbarung sorgf\u00e4ltig und vollst\u00e4ndig durch, bevor Sie die Website nutzen oder pers\u00f6nliche Informationen offenlegen.<\/p>\n\n\n\n<p>Durch die Nutzung der Website oder die Offenlegung von pers\u00f6nlichen Informationen an uns: (i) stimmen Sie zu, dass Sie die Bedingungen dieser Vereinbarung gelesen und verstanden haben, (ii) akzeptieren und stimmen Sie zu, sich an die Bedingungen dieser Vereinbarung und (iii) akzeptieren und stimmen Sie zu, alle Gesetze und Bestimmungen zu befolgen, die f\u00fcr den Gegenstand dieser Vereinbarung gelten.<\/p>\n\n\n\n<p><strong>WENN SIE NICHT MIT DEN BESTIMMUNGEN DIESER VEREINBARUNG EINVERSTANDEN SIND, GREIFEN SIE NICHT AUF DIE WEBSITE ZU ODER GEBEN PERS\u00d6NLICHE DATEN AN UNS AUS.<\/strong><\/p>\n\n\n\n<p>Die in dieser Vereinbarung enthaltenen Nutzungsbedingungen k\u00f6nnen sich von Zeit zu Zeit \u00e4ndern und jederzeit und nach eigenem Ermessen durch Aktualisierung dieser Ver\u00f6ffentlichung revidiert werden. Sie sollten diese Seite von Zeit zu Zeit besuchen, um die aktuellen Nutzungsbedingungen zu \u00fcberpr\u00fcfen, da sie f\u00fcr Sie bindend sind. Ihre fortgesetzte Nutzung der Website bedeutet, dass Sie alle \u00c4nderungen und Modifikationen dieser Vereinbarung akzeptieren. Wenn eine \u00c4nderung f\u00fcr Sie nicht akzeptabel ist, besteht Ihre einzige M\u00f6glichkeit darin, diese Vereinbarung durch Kontaktaufnahme mit dem <a href=\"&#x6d;&#97;i&#x6c;&#x74;&#111;:&#x68;&#x65;&#108;l&#x6f;&#64;l&#x75;&#x63;&#105;d&#x6d;&#x6f;&#111;n&#x73;&#46;&#99;&#x6f;&#x6d;\">Kundendienst<\/a> zu k\u00fcndigen. Gewisse Bestimmungen der Nutzungsbedingungen in dieser Vereinbarung k\u00f6nnen durch rechtliche Hinweise oder Bedingungen auf bestimmten Seiten der Website ersetzt werden.<\/p>\n\n\n\n<p>VERLUSTRISIKO \/ EIGENTUMS\u00dcBERTRAGUNG:<\/p>\n\n\n\n<p>Das Eigentumsrecht f\u00fcr die von Ihnen gekauften Produkte werden mit unserer Lieferung an den Spediteur an Sie \u00fcbertragen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2. Keine Gesundheitsberatung<\/h2>\n\n\n\n<p>Die Waren und Angaben zu bestimmten Produkten auf oder \u00fcber die Website wurden von keiner Arzneimittelbeh\u00f6rde gepr\u00fcft und sind nicht zur Diagnose, Behandlung, Heilung oder Vorbeugung von Krankheiten zugelassen.<\/p>\n\n\n\n<p>Die Website soll keine Diagnose, Behandlung oder medizinischen Rat bereitstellen. Produkte, Dienstleistungen, Informationen und andere Inhalte, die auf der Website erh\u00e4ltlich sind, einschliesslich Informationen, die direkt auf der Website zur Verf\u00fcgung gestellt werden, oder durch Verkn\u00fcpfung mit Websites von Dritten werden nur zu Informationszwecken bereitgestellt. Bitte konsultieren Sie einen Arzt oder anderes medizinisches Fachpersonal bez\u00fcglich medizinischer oder gesundheitsbezogener Diagnosen oder Behandlungsm\u00f6glichkeiten.<\/p>\n\n\n\n<p>Informationen auf dieser und dessen verlinkten Websites, einschliesslich Informationen zu medizinischen und gesundheitlichen Problemen, Behandlungen und Produkten, k\u00f6nnen in zusammengefasster Form bereitgestellt werden. Informationen auf der Website, einschliesslich Waren- oder Verpackungsbeschriftungen, sollten nicht als Ersatz f\u00fcr eine \u00e4rztliche Beratung angesehen werden. Die Website empfiehlt kein Selbstmanagement von Gesundheitsaspekten. Informationen auf der Website sind nicht umfassend und beinhalten nicht alle Krankheiten, Beschwerden, k\u00f6rperlichen Bedingungen oder deren Behandlungen. Wenden Sie sich umgehend an Ihren Arzt, wenn Sie Fragen bez\u00fcglich Ihrer Gesundheit haben. Missachten oder schieben Sie niemals den medizinischen Rat aufgrund von Informationen, die Sie auf der Website gelesen haben, auf.<\/p>\n\n\n\n<p>Links zu oder Zugriff von Websites oder Ressourcen Dritter sind keine Bef\u00fcrwortung von Informationen, Waren oder Dienstleistungen. Wir sind nicht verantwortlich f\u00fcr den Inhalt oder die Leistung von Websites Dritter. Die Nutzung von Websites Dritter erfolgt auf eigene Gefahr.<\/p>\n\n\n\n<p>Sie sollten die Informationen oder Dienste auf der Website nicht zur Diagnose oder Behandlung von Gesundheitsproblemen oder zur Verschreibung von Medikamenten oder anderen Heilverfahren verwenden. Sie sollten sich stets an Ihren Arzt wenden und die Informationen des Produktherstellers sowie jede Produkt- oder Verpackungsbeschriftung lesen, bevor Sie sich einer Behandlung von Gesundheitsproblemen unterziehen. Jede Person ist anders und kann auf verschiedene Produkte unterschiedlich reagieren. Sie sollten \u00fcber m\u00f6gliche Wechselwirkungen zwischen Medikamenten und\/oder Verh\u00fctungsmitteln, die Sie einnehmen, und der Nutzung unserer Produkte mit Ihrem Arzt sprechen.<\/p>\n\n\n\n<p>Kommentare, die von Mitarbeitern oder Website-Benutzern in Foren auf der Website gemacht werden, sind ausschliesslich ihre eigenen pers\u00f6nlichen Meinungen, die ihre eigenen individuellen Ansichten vertreten, und sind keine Stellungnahmen von uns noch vertreten sie unsere Positionen oder Ansichten. Produktbewertungen von derzeitigen oder fr\u00fcheren Mitarbeitern oder Benutzern der Website sind ausschliesslich ihre eigenen pers\u00f6nlichen Meinungen, die ihre eigenen individuellen Ansichten vertreten, und sind nicht als Ersatz f\u00fcr eine angemessene medizinische Versorgung oder \u00e4rztliche Beratung bestimmt. Wir sind nicht haftbar f\u00fcr die auf der Website angebotenen Informationen in Bezug auf Empfehlungen von Erg\u00e4nzungen f\u00fcr gesundheitliche Zwecke.<\/p>\n\n\n\n<p>\u00dcberpr\u00fcfen Sie stets die Produkt- oder Verpackungsbeschriftungen, bevor Sie ein Produkt verwenden. Wenn es Unstimmigkeiten gibt, sollten Sie die Informationen auf dem Produkt- oder Verpackungsetikett befolgen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3. Wareneink\u00e4ufe<\/h2>\n\n\n\n<p>Soweit Sie auf der Website Eink\u00e4ufe t\u00e4tigen, stimmen Sie zu, dass alle K\u00e4ufe von Waren gem\u00e4ss den bei der Bestellung angegebenen Gesch\u00e4ftsbedinungen erfolgen. Das Eigentumsrecht der von Ihnen gekauften Produkte wird mit unserer Lieferung an den Spediteur an Sie \u00fcbertragen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4. Website-Nutzung &amp; Beendigung<\/h2>\n\n\n\n<p>Indem Sie unsere Website nutzen, versichern und erkl\u00e4ren Sie, dass Sie mindestens 18 Jahre oder \u00e4lter sind und best\u00e4tigen, dass Sie vollst\u00e4ndig in der Lage und bef\u00e4higt sind, die Bedingungen, Zusicherungen und Garantien, die in dieser Vereinbarung sind, zu akzeptieren. Wenn Sie unter 18 Jahre alt sind, d\u00fcrfen Sie diese Website nicht nutzen oder an einem Programm teilnehmen.<\/p>\n\n\n\n<p>Sie erkl\u00e4ren sich damit einverstanden, genaue, wahrheitsgetreue, vollst\u00e4ndige und aktuelle Informationen \u00fcber Sie auf Aufforderung durch die Website bereitzustellen und diese Informationen umgehend zu aktualisieren, um genaue, wahrheitsgem\u00e4sse, vollst\u00e4ndige und aktuelle Informationen zu gew\u00e4hrleisten. Wenn Sie unsachgem\u00e4sse, falsche, unvollst\u00e4ndige oder veraltete Informationen zur Verf\u00fcgung stellen oder wir nach eigenem Ermessen vermuten, dass diese Informationen unsachgem\u00e4ss, falsch, unvollst\u00e4ndig oder veraltet sind, behalten wir uns das Recht vor, Ihr Konto zu sperren oder zu k\u00fcndigen und jegliche aktuelle oder zuk\u00fcnftige Nutzung der Website oder eines Teils davon zu untersagen. F\u00fcr die Registrierung m\u00fcssen Sie einen Benutzernamen und ein Passwort erstellen. Sie sind verantwortlich f\u00fcr die Vertraulichkeit Ihres Kontos und Passworts und tragen die volle Verantwortung f\u00fcr alle Aktivit\u00e4ten, die durch Ihr Konto oder Passwort stattfinden. Sie stimmen zu, uns unverz\u00fcglich \u00fcber eine unbefugte Verwendung Ihres Kontos oder Passworts oder eine andere Sicherheitsverletzung zu informieren und sicherzustellen, dass Sie am Ende jeder Sitzung Ihr Konto ordnungsgem\u00e4ss verlassen. Sie vereinbaren, f\u00fcr alle Geb\u00fchren verantwortlich zu sein, die sich aus der Nutzung Ihres Webseitenkontos ergeben, einschliesslich der Geb\u00fchren, die aus der nicht autorisierten Nutzung Ihres Kontos resultieren. Wir haften nicht f\u00fcr Verluste oder Sch\u00e4den, die aus der Nichtbeachtung dieses Absatzes resultieren.<\/p>\n\n\n\n<p>Sie stimmen zu, die Website f\u00fcr rechtm\u00e4ssige Zwecke zu nutzen und die Verantwortung f\u00fcr Ihre Nutzung und Kommunikation auf der Website zu tragen. Sie verpflichten sich, keine ungesetzlichen, rechtsverletzenden, verleumderischen, obsz\u00f6nen, bedrohenden, beleidigenden oder anderweitig anst\u00f6ssigen Inhalte jeglicher Art auf der Website zu posten oder zu \u00fcbermitteln, einschliesslich Material, das rechtswidriges Verhalten oder zivilrechtliche Haftung f\u00f6rdert oder Rechte Anderer an geistigem Eigentum verletzen w\u00fcrde oder auf andere Weise gegen geltendes lokales, staatliches, nationales oder internationales Recht verstossen. Sie stimmen zu, die Website nicht in einer Weise zu verwenden, die den normalen Betrieb beeintr\u00e4chtigt oder die Nutzung der Website durch Dritte beeintr\u00e4chtigt.<\/p>\n\n\n\n<p>Sie erkl\u00e4ren sich damit einverstanden, auf keinem anderen Weg als \u00fcber die von uns bereitgestellte Schnittstelle auf die Website zuzugreifen. Das Anzeigen oder Ausf\u00fchren der Website oder von Informationen oder Materialien, die auf der Website in Frames oder auf \u00e4hnliche Weise auf einer anderen Website ohne unsere vorherige Genehmigung angezeigt werden, ist untersagt. Alle erlaubten Links zu der Website m\u00fcssen allen geltenden Gesetzen, Regeln und Vorschriften entsprechen.<\/p>\n\n\n\n<p>Wir geben keine Zusicherung, dass die auf der Website enthaltenen Materialien oder die auf der Website beschriebenen oder angebotenen Produkte passend oder verf\u00fcgbar f\u00fcr den Gebrauch in Orten ausserhalb der Schweiz sind oder dass diese Vereinbarung den Gesetzen eines anderen Landes entspricht. Benutzer der Website ausserhalb der Schweiz tun dies auf eigene Initiative und Gefahr und sind verantwortlich f\u00fcr die Einhaltung aller geltenden Gesetze und Vorschriften. Sie vereinbaren, nicht auf die Website von einem Ort oder Gebiet zuzugreifen, in dem ihre Inhalte illegal sind und dass Sie und nicht wir f\u00fcr die Einhaltung aller geltenden Gesetze und Vorschriften verantwortlich sind.<\/p>\n\n\n\n<p>Dieser Vertrag ist g\u00fcltig, bis er von uns oder Ihnen gek\u00fcndigt wird. Wir k\u00f6nnen nach eigenem Ermessen diesen Vertrag jederzeit ohne Vorank\u00fcndigung sperren oder k\u00fcndigen und Ihnen den Zugriff auf die Website oder einen Teil davon verweigern. Sie k\u00f6nnen diese Vereinbarung jederzeit k\u00fcndigen, indem Sie sich an den <a href=\"&#109;a&#x69;l&#x74;o&#x3a;h&#x65;l&#x6c;o&#x40;&#108;&#x75;&#99;&#x69;&#100;&#x6d;&#111;&#x6f;&#110;&#x73;&#46;&#x63;&#111;m\">Kundendienst<\/a> wenden und die Nutzung der Website einstellen. Nach der K\u00fcndigung durch uns oder Sie m\u00fcssen Sie alle von der Website erhaltenen Materialien vernichten, einschliesslich aller Kopien solcher Materialien, die gem\u00e4ss den in dieser Vereinbarung enthaltenen Nutzungs- oder anderweitigen Bedingungen unterliegen. Wir behalten uns das Recht vor, die Website oder einen Teil davon vor\u00fcbergehend oder dauerhaft, mit Benachrichtigung an Sie, zu \u00e4ndern oder einzustellen.<\/p>\n\n\n\n<p>Wir behalten uns das Recht vor, Ihr Konto zu k\u00fcndigen, wenn Ihre Bestellung als betr\u00fcgerisch gilt oder Kreditkartenbuchungen bestritten werden. Sie stimmen zu, dass wir Ihren Zugriff auf die gesamte Website oder einen Teil davon beenden oder sperren, mit oder ohne Benachrichtigung an Sie, f\u00fcr Verhalten, das wir nach unserem Ermessen als Verstoss gegen einen Teil dieser Vereinbarung, Gesetze oder Vorschriften ansehen, sch\u00e4dlich f\u00fcr einen anderen Benutzer, uns oder unsere verbundenen Unternehmen sind.<\/p>\n\n\n\n<p>Folgendes soll nach Beendigung des Vertrags entweder durch uns oder Sie, erhalten bleiben; Datenschutz, Haftungsausschluss, salvatorische Klausel; Interpretation und Verschiedenes.<\/p>\n\n\n\n<p>Einige Bereiche der Site implementieren Google Maps \/ Google Earth-Kartendienste. Ihre Nutzung von Google Maps \/ Google Earth unterliegt den <a href=\"https:\/\/maps.google.com\/help\/terms_maps.html\" target=\"_blank\" rel=\"noopener\">zus\u00e4tzlichen Nutzungsbedingungen von Google Maps\/Google Earth<\/a> und den <a href=\"https:\/\/policies.google.com\/privacy?hl=en&amp;gl=us\" target=\"_blank\" rel=\"noopener\">Datenschutzbestimmungen von Google<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">6. Datenschutz<\/h2>\n\n\n\n<p>Ihre Privatsph\u00e4re und Sicherheit hat bei Lucid Moons oberste Priorit\u00e4t. Bitte lesen Sie Lucid Moons\u2019s <a href=\"https:\/\/lucidmoons.com\/de-ch\/datenschutzerklaerung\/\">Datenschutzrichtlinie<\/a>, die f\u00fcr die auf der Website erh\u00e4ltlichen oder von Ihnen bereitgestellten pers\u00f6nlichen Informationen gelten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">7. Haftungsausschluss<\/h2>\n\n\n\n<p>SIE ERKL\u00c4REN SICH DAMIT EINVERSTANDEN, DASS DIE NUTZUNG DER WEBSITE AUF IHR EIGENES RISIKO ERFOLGT. DIE WEBSITE UND DIE HIERIN ENTHALTENEN MATERIALIEN WERDEN \u201eOHNE M\u00c4NGELGEW\u00c4HR\u201c UND \u201eWIE VORLIEGEND\u201c ZUR VERF\u00dcGUNG GESTELLT, SOFERN ES NICHT AUSDR\u00dcCKLICH ANDERS IN DIESER VEREINBARUNG BESTIMMT WIRD. LUCID MOONS UND ANDERE VERBUNDENE UNTERNEHMEN UND IHRE JEWEILIGEN AMTSTR\u00c4GER, DIREKTOREN, MITARBEITER UND ANDEREN VERTRETER, NACHFOLGER UND ZUGEORDNETEN EINES JEDEN (ZUSAMMENFASSEND \u201eLUCID MOONS-BETEILIGUNGSGESELLSCHAFTEN\u201c) LEHNEN ALLE GEW\u00c4HRLEISTUNGEN IRGENDEINER ART AB, OB AUSDR\u00dcCKLICH ODER STILLSCHWEIGEND, EINSCHLIESSLICH, ABER NICHT BESCHR\u00c4NKT AUF DIE STILLSCHWEIGENDEN GEW\u00c4HRLEISTUNGEN ALLGEMEINER HANDELSTAUGLICHKEIT, EIGNUNG F\u00dcR EINEN BESTIMMTEN ZWECK UND NICHTVERLETZUNG VON RECHTEN.<\/p>\n\n\n\n<p>LUCID MOONS-BETEILIGUNGSGESELLSCHAFTEN \u00dcBERNEHMEN KEINE GEW\u00c4HRLEISTUNG, DASS DIE WEBSITE ODER EIN PROGRAMM IHRE ANFORDERUNGEN ERF\u00dcLLT, DIE WEBSITE ZEITLICH, SICHER, FEHLERFREI ODER UNUNTERBROCHEN IST, DASS DIE ERGEBNISSE, DIE VON DER WEBSITE ODER VON EINEM PROGRAMM BEZOGEN WERDEN, GENAU ODER ZUVERL\u00c4SSIG SIND, DASS DIE QUALIT\u00c4T VON PRODUKTEN, DIENSTLEISTUNGEN, INFORMATIONEN ODER ANDEREM MATERIAL, DAS SIE DURCH DIE WEBSITE ERHALTEN, IHRE ERWARTUNGEN ERF\u00dcLLEN WERDEN, UND JEGLICHE FEHLER AN DER WEBSITE BEHOBEN WERDEN. JEGLICHES HERUNTERGELADENES ODER ANDERWEITIG DURCH DIE WEBSITE ODER \u00dcBER PROGRAMME ERWORBENES MATERIAL ERFOLGT AUF IHR EIGENES RISIKO UND SIE ALLEIN SIND VERANTWORTLICH F\u00dcR SCH\u00c4DEN AN IHREM COMPUTERSYSTEM ODER DEN VERLUST VON DATEN, DER DURCH DAS HERUNTERLADEN VON MATERIALIEN ENTSTANDEN IST. KEINE VON IHNEN DURCH DIE WEBSITE ODER DURCH EIN PROGRAMM BEZOGENEN INFORMATIONEN ERSTELLEN EINE GARANTIE IN BEZUG AUF DIE WEBSITE ODER EIN PROGRAMM DAR, DAS NICHT AUSDR\u00dcCKLICH IN DIESER VEREINBARUNG BESTIMMT IST.<\/p>\n\n\n\n<p>SOWEIT GESETZLICH ZUL\u00c4SSIG, LEHNEN LUCID MOONS-BETEILIGUNGSGESELLSCHAFTEN ALLE GEW\u00c4HRLEISTUNGEN IRGENDEINER ART AB, OB AUSDR\u00dcCKLICH ODER STILLSCHWEIGEND, EINSCHLIESSLICH, ABER NICHT BESCHR\u00c4NKT AUF DIE GEW\u00c4HRLEISTUNGEN ALLGEMEINER HANDELSTAUGLICHKEIT UND EIGNUNG F\u00dcR EINEN BESTIMMTEN ZWECK IN BEZUG AUF DIE DURCH DIE WEBSITE ERWORBENEN PRODUKTE UND DIENSTLEISTUNGEN UND IHRE TEILNAHME AN EINEM DER VERF\u00dcGBAREN PROGRAMME. OHNE EINSCHR\u00c4NKUNG DER EBEN BESCHRIEBENEN VORAUSSETZUNGEN LEHNEN LUCID MOONS-BETEILIGUNGSGESELLSCHAFTEN, IM GESETZLICH ZUL\u00c4SSIGEN UMFANG, AUSDR\u00dcCKLICH DIE HAFTUNG F\u00dcR PRODUKTM\u00c4NGEL ODER -FEHLER, NORMALEN VERSCHLEISS, PRODUKTMISSBRAUCH ODER MODIFIKATION, FEHLGEBRAUCH, FALSCHE PRODUKTWAHL UND DAS NICHTBEFOLGEN GEDRUCKTER ANLEITUNGEN, AB.<\/p>\n\n\n\n<p>IM GESETZLICH ZUL\u00c4SSIGEN UMFANG HAFTEN LUCID MOONS-BETEILIGUNGSGESELLSCHAFTEN IN KEINEM FALL F\u00dcR INDIREKTE, BEIL\u00c4UFIGE, BESONDERE ODER FOLGESCH\u00c4DEN (EINSCHLIESSLICH SCH\u00c4DEN DURCH GESCH\u00c4FTSVERLUSTE, GEWINNVERLUSTE, VERLUSTE VON KUNDENVERTRAUEN, NUTZUNGSSCH\u00c4DEN, VERLUST VON DATEN, KOSTEN F\u00dcR DIE BESCHAFFUNG VON ERSATZG\u00dcTERN, DIENSTLEISTUNGEN ODER INFORMATIONEN, RECHTSSTREITIGKEITEN ODER \u00c4HNLICHES), GANZ GLEICH, OB DIESE SCH\u00c4DEN DURCH EINE VERTRAGSVERLETZUNG, GARANTIEVERLETZUNG, EINE UNERLAUBTE HANDLUNG (EINSCHLIESSLICH FAHRL\u00c4SSIGKEIT), PRODUKTHAFTUNG ODER AUF ANDEREM WEGE ENTSTANDEN SIND, AUCH WENN LUCID MOONS-BETEILIGUNGSGESELLSCHAFTEN AUF DIE M\u00d6GLICHKEIT SOLCHER SCH\u00c4DEN HINGEWIESEN WURDE. DIE HIER BESCHRIEBENEN HAFTUNGSBESCHR\u00c4NKUNGEN SIND WESENTLICHE BESTANDTEILE DER GRUNDLAGE DER VEREINBARUNG ZWISCHEN LUCID MOONS UND IHNEN. DIE PRODUKTE, INFORMATIONEN, UND DIENSTLEISTUNGEN, DIE AUF UND \u00dcBER DIE WEBSITE ANGEBOTEN WERDEN, WERDEN OHNE DIESE BESCHR\u00c4NKUNGEN NICHT BEREITGESTELLT. VORBEHALTLICH DES VORSTEHENDEN, SOWEIT GESETZLICH ZUL\u00c4SSIG: (I) WENN SIE EIN KUNDE SIND, IST DIE MAXIMALE HAFTUNG VON LUCID MOONS F\u00dcR DIE VON IHNEN BEZAHLTEN PRODUKTE, INFORMATIONEN ODER SERVICE VON LUCID MOONS BEGRENZT AUF DEN VON IHNEN GEZAHLTEN BETRAG, UND (II) WENN SIE EIN PROGRAMMTEILNEHMER SIND, IST DIE MAXIMALE HAFTUNG VON LUCID MOONS IST AUF DEN VON LUCID MOONS, IM RAHMEN DES ANWENDBAREN PROGRAMMS W\u00c4HREND 12 MONATEN VOR DEM HAFTUNGSF\u00c4HIGEN ZEITPUNKT, BERECHNETEN ODER GEZAHLTEN BETRAG BESCHR\u00c4NKT.<\/p>\n\n\n\n<p>DA EINIGE STAATEN UND \/ ODER GERICHTSBARKEITEN DEN HAFTUNGSAUssCHLUss BESTIMMTER GEW\u00c4HRLEISTUNGEN, DIE HAFTUNGSBESCHR\u00c4NKUNG ODER DEN HAFTUNGSAUssCHLUss F\u00dcR BESTIMMTE SCHADENSARTEN NICHT ZULAssEN, K\u00d6NNEN EINIGE DER OBEN GENANNTEN HAFTUNGSAUssCHL\u00dcssE UND BESCHR\u00c4NKUNGEN NICHT AUF SIE ZUTREFFEN. WENN SIE MIT EINEM TEIL DER WEBSITE, IHRER TEILNAHME AN EINEM PROGRAMM ODER MIT EINER DER IN DIESER VEREINBARUNG ENTHALTENEN NUTZUNGSBEDINGUNGEN UNZUFRIEDEN SIND, IST IHR EINZIGES UND AUssCHLIEssLICHES RECHTSMITTEL, DIE NUTZUNG DER WEBSITE ODER DIE TEILNAHME AN DEM ANWENDBAREN PROGRAMM EINZUSTELLEN. IN NEW JERSEY GELTEN DIE SCHADLOSKLAUSELN NICHT F\u00dcR IHRE HAFTUNG, DIE AUF VORS\u00c4TZLICHEM ODER R\u00dcCKSICHTSLOSEM VERHALTEN, GROBER FAHRL\u00c4ssIGKEIT, VERSCHULDENSUNABH\u00c4NGIGER HAFTUNG ODER VERLETZUNG EINER GESETZLICH VORGESCHRIEBENEN PFLICHT SEITENS LUCID MOONS BERUHEN.<\/p>\n\n\n\n<p>WIR GEBEN KEINE GARANTIE ODER GEW\u00c4HRLEISTUNG HINSICHTLICH DER VERKAUFTEN PRODUKTE ODER DIENSTLEISTUNGEN. WIR SIND F\u00dcR SCH\u00c4DEN F\u00dcR INFORMATIONEN, PRODUKTE ODER DIENSTLEISTUNGEN, DIE VON DRITTEN ZUR VERF\u00dcGUNG GESTELLT WERDEN, NICHT VERANTWORTLICH, AUCH WENN WIR AUF DIE M\u00d6GLICHKEIT VON SCH\u00c4DEN HINGEWIESEN WURDEN. IN NEW JERSEY GELTEN DIE SCHADLOSKLAUSELN NICHT F\u00dcR IHRE HAFTUNG, DIE AUF VORS\u00c4TZLICHEM ODER R\u00dcCKSICHTSLOSEM VERHALTEN, GROBER FAHRL\u00c4ssIGKEIT, VERSCHULDENSUNABH\u00c4NGIGER HAFTUNG ODER VERLETZUNG EINER GESETZLICH VORGESCHRIEBENEN PFLICHT SEITENS LUCID MOONS BERUHEN.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">8. Entsch\u00e4digung<\/h2>\n\n\n\n<p>Sie verpflichten sich, Lucid Moons von allen Sch\u00e4den, Ausgaben, Kosten und Sch\u00e4den freizustellen, einschliesslich Anwaltskosten, die sich aus Ihrer Nutzung oder Kontaktaufnahme auf der Website, Ihrer Nutzung oder Ihrer Unf\u00e4higkeit zur Nutzung der Website oder Dienstleistungen ergeben, Produkte oder Dienstleistungen, die Sie in Verbindung mit der Website gekauft oder erhalten haben, jegliche Website-Beitr\u00e4ge oder -Aktivit\u00e4ten in Bezug auf Ihr Konto von Ihnen oder einer anderen Person, eine Verletzung Ihrerseits von Bedingungen dieser Vereinbarung, Rechte eines Dritten oder geltender Gesetze, Regeln oder Vorschriften. Sie stimmen zu, so kooperativ wie n\u00f6tig zusammenzuarbeiten, um Anspr\u00fcche geltend zu machen. Wir behalten uns das Recht vor, die ausschliessliche Verteidigung und Kontrolle der von Ihnen zu entsch\u00e4digenden Angelegenheiten zu \u00fcbernehmen. In diesem Fall m\u00fcssen Sie uns zus\u00e4tzlich zu den entstandenen Verlusten, Anspr\u00fcchen, Sch\u00e4den und Verbindlichkeiten unsere Anwaltsgeb\u00fchren und -kosten erstatten. In keinem Fall d\u00fcrfen Sie ohne vorherige schriftliche Zustimmung von Lucid Moons eine Einigung in einer Angelegenheit herbeif\u00fchren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">9. Urheberschutzrechte, Handelszeichen und andere geistige Eigentumsrechte<\/h2>\n\n\n\n<p>Sie erkennen an, dass alle Materialien auf der Website einschliesslich Design, Text, Grafiken, Sounds, Bildern, Software und anderen Dateien der Website, sowie deren Auswahl und Anordnung (zusammen \u201eMaterialien\u201c), unser Eigentum ist und durch Schweizer und internationalem Urheberrecht oder andere Gesetze und Rechte des geistigen Eigentums unterliegt und gesch\u00fctzt ist. Die auf der Website enthaltenen Warenzeichen, Marken f\u00fcr Waren und Dienstleistungen, Handelsnamen und Logos (zusammenfassend als \u201eMarken\u201c bezeichnet), sind einschliesslich und ohne Einschr\u00e4nkung Lucid Moons\u00ae und alleiniges Eigentum von Lucid Moons. Alle Seitenk\u00f6pfe, benutzerdefinierte Grafiken und Symbole Marken von Lucid Moons. Lucid Moons gew\u00e4hrt Ihnen eine eingeschr\u00e4nkte nicht-exklusive, nicht-\u00fcbertragbare, widerrufbare Lizenz zum Zugriff und zur Nutzung der Materialien und Marken nur in der von Lucid Moons f\u00fcr Ihre pers\u00f6nliche und nicht kommerzielle Nutzung zugelassenen Weise (die \u201eLizenz\u201c). Diese Lizenz bleibt in Kraft, bis dieser Vertrag von Ihnen oder uns in \u00dcbereinstimmung mit dieser Vereinbarung gek\u00fcndigt wird. Jegliche unbefugte Nutzung der Materialien oder Marken ist Grund f\u00fcr die K\u00fcndigung der Lizenz. Alle hier nicht ausdr\u00fccklich gew\u00e4hrten Rechte sind Lucid Moons und seinen Lizenzgebern vorbehalten. Andere Urheberrechte, Marken, Produktnamen, Firmennamen, Logos oder geistiges Eigentum sind Eigentum der jeweiligen Inhaber mit allen Rechten vorbehalten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">10. Vereinbarung<\/h2>\n\n\n\n<p>Diese Vereinbarung stellt die einzige Vereinbarung zwischen uns und Ihnen in Bezug auf den Gegenstand dieser Vereinbarung dar. Diese Vereinbarung ersetzt alle fr\u00fcheren oder gleichzeitigen Abkommen, Darstellungen, Garantien und Verst\u00e4ndnis, gleich ob schriftlich oder m\u00fcndlich, in Bezug auf den Gegenstand dieser Vereinbarung.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">11. Salvatorische Klausel; Interpretation<\/h2>\n\n\n\n<p>Wenn eine Bestimmung dieser Vereinbarung f\u00fcr nichtig, unrechtm\u00e4ssig oder aus anderen Gr\u00fcnden nicht durchsetzbar erkl\u00e4rt wird, wird diese Bestimmung von dieser Vereinbarung getrennt und der Rest dieser Vereinbarung bleibt in Kraft. Bei der Verwendung in dieser Vereinbarung werden unter dem Begriff \u201eeinschliesslich\u201c die W\u00f6rter \u201eohne Einschr\u00e4nkung\u201c verstanden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">12. Geltendes Recht; Zust\u00e4ndigkeit; Streitbeilegung und Sammelklageverzicht<\/h2>\n\n\n\n<p>Alle Fragen in Bezug auf die Verfassung, G\u00fcltigkeit, Durchsetzung und Auslegung dieses Vertrags unterliegen dem Schweizer Recht und sind unter Ausschluss von Rechtswahlklauseln oder kollisionsrechtlichen Vorschriften in \u00dcbereinstimmung mit diesem auszulegen, ohne dass eine Rechtswahl oder ein Gesetzeskonflikt ber\u00fchrt wird.<\/p>\n\n\n\n<p>Soweit gesetzlich zul\u00e4ssig, vereinbaren Sie und die Lucid Moons-Beteiligungsgesellschaften, Streitigkeiten, Meinungsverschiedenheiten oder Anspr\u00fcche zu schlichten, die sich aus oder im Zusammenhang mit dieser Vereinbarung ergeben, einschliesslich, aber nicht beschr\u00e4nkt auf Anspr\u00fcche, die aufgrund von Verletzungen des Vertrages, unerlaubter Handlung, Fahrl\u00e4ssigkeit, Rechtsvorschriften oder Bestimmungen stammen. JEDE PARTEI GIBT DAS RECHT AUF, GERICHTLICHE SCHRITTE ZU UNTERNEHMEN UND VON RICHTER ODER EINER JURY AUFGRUND JEGLICHER DISPUTE, ANSPR\u00dcCHE ODER STREITIGKEITEN ANGEH\u00d6RT ZU WERDEN.<\/p>\n\n\n\n<p>SIE UND IHRE HERAUSGEBER VEREINBAREN AUSDR\u00dcCKLICH, F\u00dcR SCH\u00c4DEN, ANSPR\u00dcCHE ODER STREITIGKEITEN, DIE SICH AUS ODER IN IRGENDEINER WEISE IM ZUSAMMENHANG MIT DIESER VEREINBARUNG ERGEBEN, AUFZUKOMMEN. DIESE SCHIEDSGERICHTVEREINBARUNG GILT EBENSO F\u00dcR GRENZWERTIGE ANGELEGENHEITEN BETREFFEND DER SCHIEDSF\u00c4HIGKEIT, EINSCHLIESSLICH ASPEKTE DER UNZUMUTBARKEIT ODER ILLEGALIT\u00c4T DER VEREINBARUNG SOWIE JEGLICHE VERTEIDIGUNG. SIE STIMMEN FERNER ZU, DASS JEDES SCHIEDSVERFAHREN NUR ALS EINZELVERFAHREN AN IHRER UND AN UNSEREN INDIVIDUELLEN KAPAZIT\u00c4TEN AUSGEF\u00dcHRT WERDEN KANN, NICHT ALS GRUPPENKLAGE, SAMMELKLAGE ODER VERBANDSKLAGE. DAS SCHIEDSGERICHT KANN NICHT MEHR ALS EINEN ANSPRUCH EINER EINZELPERSON ODER GESELLSCHAFT KONSOLIDIEREN UND DARF NICHT \u00dcBER VERBANDSKLAGEN ODER GRUPPENVERFAHREN PR\u00c4SIDEN.<\/p>\n\n\n\n<p>Die gegenseitige Vereinbarung zwischen Ihnen und den Lucid Moons-Beteiligungsgesellschaften, alle Streitigkeiten auf individueller Basis, anstatt vor den Gerichten oder anderen Instanzen zu verhandeln, zu schlichten, gilt als gegenseitige Beachtung dieser Schiedsvereinbarung.<\/p>\n\n\n\n<p>Jede Partei kann das Recht zur Schlichtung aus\u00fcben, indem sie die andere Partei schriftlich \u00fcber alle Anspr\u00fcche, welche die Grundlage f\u00fcr ein solches Recht bilden, in ausreichendem Detail informiert, um die andere Partei \u00fcber den Inhalt solcher Anspr\u00fcche zu informieren. In keinem Fall darf der Antrag auf ein Schiedsverfahren nach dem Zeitpunkt gestellt werden, zu dem die Einleitung eines Rechts- oder Billigkeitsverfahrens aufgrund dieser Anspr\u00fcche durch die anwendbare Verj\u00e4hrungsfrist ausgeschlossen w\u00e4re.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">13. Sonstiges<\/h2>\n\n\n\n<p>Sie sind nicht berechtigt, diesen Vertrag ohne unsere vorherige schriftliche Zustimmung kraft Gesetzes oder anderweitig zu \u00fcbertragen. Vorbehaltlich dieser Einschr\u00e4nkung ist diese Vereinbarung f\u00fcr die Parteien und deren jeweilige Rechtsnachfolger und Abtretungsempf\u00e4nger bindend und vollstreckbar.<\/p>\n\n\n\n<p>Das Vers\u00e4umnis vonseiten Lucid Moons, die in dieser Vereinbarungen enthaltenen Bestimmungen, durchzusetzen, oder auf eine Verletzung durch Sie, stellt in keinem Fall einen Verzicht auf sein Recht dar, oder beschr\u00e4nkt das Recht dieser Partei auf strikte Einhaltung dieser oder einer anderen Bedingung in dieser Vereinbarung. Sie stimmen zu, dass unabh\u00e4ngig von gegenteiligen Statuten oder Gesetzen muss jeder Anspruch oder Klageanspruch, der sich aus der Nutzung dieser Website oder dieser Vereinbarung ergibt oder sich ergeben, innerhalb eines (1) Jahres nach der Entstehung eines solchen Anspruchs oder Klagegrundes geltend gemacht werden m\u00fcssen. Ein solcher Anspruch oder Klagegrund wird dauerhaft ausgeschlossen. Die \u201eBestimmungen dieses Haftungsausschlusses\u201c in dieser Vereinbarung kommen den hier definierten Lucid Moons-Beteiligungsgesellschaften zugute, und jede dieser Personen oder Organisationen hat das Recht, diese Bestimmungen direkt gegen Sie in ihrem eigenen Namen geltend zu machen und durchzusetzen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Kontaktieren Sie uns:<\/h2>\n\n\n\n<p>Wenn Sie Fragen zu diesem Vertrag haben, wenden Sie sich an unseren <a href=\"&#x6d;&#x61;&#105;lt&#x6f;&#x3a;&#104;&#101;l&#x6c;&#x6f;&#64;&#108;u&#x63;&#x69;&#x64;&#109;oo&#x6e;&#x73;&#46;&#99;o&#x6d;\">Kundendienst.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Allgemeine Gesch\u00e4ftsbedingungen (AGB) Stand: 30.07.2018 Geltung der Allgemeinen Gesch\u00e4ftsbedingungen Diese Allgemeinen Gesch\u00e4ftsbedingungen (nachfolgend \u201eAGB\u201c genannt) gelten f\u00fcr alle Vertr\u00e4ge, die \u00fcber den Online-Shop www.lucidmoons.com zwischen der Lucid Moons GmbH und Kunden abgeschlossen werden, die Verbraucher sind. Verbraucher ist jede nat\u00fcrliche Person, die ein Rechtsgesch\u00e4ft zu einem Zwecke abschliesst, der weder ihrer gewerblichen noch ihrer selbstst\u00e4ndigen&nbsp;\u2026<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-16434","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lucidmoons.com\/de-ch\/wp-json\/wp\/v2\/pages\/16434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lucidmoons.com\/de-ch\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lucidmoons.com\/de-ch\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lucidmoons.com\/de-ch\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lucidmoons.com\/de-ch\/wp-json\/wp\/v2\/comments?post=16434"}],"version-history":[{"count":4,"href":"https:\/\/lucidmoons.com\/de-ch\/wp-json\/wp\/v2\/pages\/16434\/revisions"}],"predecessor-version":[{"id":19821,"href":"https:\/\/lucidmoons.com\/de-ch\/wp-json\/wp\/v2\/pages\/16434\/revisions\/19821"}],"wp:attachment":[{"href":"https:\/\/lucidmoons.com\/de-ch\/wp-json\/wp\/v2\/media?parent=16434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}